{"id":2000,"count":12,"description":"","link":"https:\/\/www.onelifediagnosticos.com.br\/blog\/category\/check-up\/","name":"check-up","slug":"check-up","taxonomy":"category","parent":0,"meta":[],"_links":{"self":[{"href":"https:\/\/www.onelifediagnosticos.com.br\/blog\/wp-json\/wp\/v2\/categories\/2000","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.onelifediagnosticos.com.br\/blog\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/www.onelifediagnosticos.com.br\/blog\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/www.onelifediagnosticos.com.br\/blog\/wp-json\/wp\/v2\/posts?categories=2000"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}